{"id":5,"count":5,"description":"","link":"https:\/\/odesa.insay-spa.com.ua\/ru\/classic-massage\/masazhi-z-korekcziyi-figury-2\/","name":"\u041c\u0430\u0441\u0441\u0430\u0436\u0438 \u043f\u043e \u043a\u043e\u0440\u0440\u0435\u043a\u0446\u0438\u0438 \u0444\u0438\u0433\u0443\u0440\u044b","slug":"masazhi-z-korekcziyi-figury-2","taxonomy":"type-massage","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/odesa.insay-spa.com.ua\/ru\/wp-json\/wp\/v2\/type-massage\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.insay-spa.com.ua\/ru\/wp-json\/wp\/v2\/type-massage"}],"about":[{"href":"https:\/\/odesa.insay-spa.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/type-massage"}],"wp:post_type":[{"href":"https:\/\/odesa.insay-spa.com.ua\/ru\/wp-json\/wp\/v2\/massage?type-massage=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}